{"id":49681,"date":"2026-02-25T17:00:00","date_gmt":"2026-02-25T10:00:00","guid":{"rendered":"https:\/\/roietmunicipal.go.th\/roiet\/?p=49681"},"modified":"2026-02-25T19:57:23","modified_gmt":"2026-02-25T12:57:23","slug":"%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47","status":"publish","type":"post","link":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/","title":{"rendered":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 25 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e40\u0e27\u0e25\u0e32 17.00 \u0e19. \u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e2b\u0e2d\u0e42\u0e2b\u0e27\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e32\u0e1a\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e02\u0e2d\u0e1e\u0e23\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e34\u0e48\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e21\u0e07\u0e04\u0e25 \u0e2a\u0e34\u0e48\u0e07\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e0a\u0e31\u0e0a\u0e27\u0e32\u0e25\u0e22\u0e4c \u0e40\u0e1a\u0e0d\u0e08\u0e28\u0e34\u0e23\u0e34\u0e27\u0e07\u0e28\u0e4c \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e13 \u0e2b\u0e2d\u0e42\u0e2b\u0e27\u0e14\u0e51\u0e50\u0e51 Roi Et Tower<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1706\" data-id=\"49685\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-6-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49685\" srcset=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-6-Copy-scaled.jpg 2560w, https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-6-Copy-scaled-360x240.jpg 360w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49688\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0541-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49688\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49686\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0550-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49686\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49683\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0557-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49683\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49687\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0561-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49687\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49682\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0563-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49682\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49684\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0564-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49684\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49689\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0569-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49689\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49690\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0571-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49690\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49691\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0572-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49691\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49692\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0582-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49692\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49693\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_0590-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49693\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 25 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e40\u0e27\u0e25\u0e32 17.00 \u0e19. \u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08 [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":49685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-49681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-7"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/roietmunicipal.go.th\/roiet\/\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07-\u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c-47\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 25 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e40\u0e27\u0e25\u0e32 17.00 \u0e19. \u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/roietmunicipal.go.th\/roiet\/\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07-\u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c-47\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prmuni101\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-25T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T12:57:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-6-Copy-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/\"},\"author\":{\"name\":\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#\\\/schema\\\/person\\\/8976f4ad5f8ef9e77928f898640ecb3f\"},\"headline\":\"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"datePublished\":\"2026-02-25T10:00:00+00:00\",\"dateModified\":\"2026-02-25T12:57:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/\"},\"wordCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1-6-Copy-scaled.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/\",\"name\":\"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1-6-Copy-scaled.jpg\",\"datePublished\":\"2026-02-25T10:00:00+00:00\",\"dateModified\":\"2026-02-25T12:57:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/#primaryimage\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1-6-Copy-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1-6-Copy-scaled.jpg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#website\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/\",\"name\":\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"description\":\"\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48 \u0e1c\u0e39\u0e49\u0e04\u0e19\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01 \u0e1f\u0e39\u0e21\u0e1f\u0e31\u0e01\u0e15\u0e33\u0e19\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e25\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\",\"publisher\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#organization\",\"name\":\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo101.png\",\"contentUrl\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo101.png\",\"width\":800,\"height\":830,\"caption\":\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\"},\"image\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prmuni101\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/roietmuni\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#\\\/schema\\\/person\\\/8976f4ad5f8ef9e77928f898640ecb3f\",\"name\":\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g\",\"caption\":\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\"},\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/author\\\/jitlada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/roietmunicipal.go.th\/roiet\/\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07-\u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c-47\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","og_description":"\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 25 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e40\u0e27\u0e25\u0e32 17.00 \u0e19. \u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08 [&hellip;]","og_url":"https:\/\/roietmunicipal.go.th\/roiet\/\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07-\u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c-47\/","og_site_name":"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","article_publisher":"https:\/\/www.facebook.com\/prmuni101\/","article_published_time":"2026-02-25T10:00:00+00:00","article_modified_time":"2026-02-25T12:57:23+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-6-Copy-scaled.jpg","type":"image\/jpeg"}],"author":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c","Est. reading time":"3 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/#article","isPartOf":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/"},"author":{"name":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#\/schema\/person\/8976f4ad5f8ef9e77928f898640ecb3f"},"headline":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","datePublished":"2026-02-25T10:00:00+00:00","dateModified":"2026-02-25T12:57:23+00:00","mainEntityOfPage":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/"},"wordCount":3,"publisher":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/#organization"},"image":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/#primaryimage"},"thumbnailUrl":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-6-Copy-scaled.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/","url":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/","name":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","isPartOf":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/#website"},"primaryImageOfPage":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/#primaryimage"},"image":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/#primaryimage"},"thumbnailUrl":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-6-Copy-scaled.jpg","datePublished":"2026-02-25T10:00:00+00:00","dateModified":"2026-02-25T12:57:23+00:00","breadcrumb":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/#primaryimage","url":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-6-Copy-scaled.jpg","contentUrl":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-6-Copy-scaled.jpg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-47\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/roietmunicipal.go.th\/roiet\/"},{"@type":"ListItem","position":2,"name":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e14\u0e23. \u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14"}]},{"@type":"WebSite","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#website","url":"https:\/\/roietmunicipal.go.th\/roiet\/","name":"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","description":"\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48 \u0e1c\u0e39\u0e49\u0e04\u0e19\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01 \u0e1f\u0e39\u0e21\u0e1f\u0e31\u0e01\u0e15\u0e33\u0e19\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e25\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","publisher":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/roietmunicipal.go.th\/roiet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#organization","name":"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","url":"https:\/\/roietmunicipal.go.th\/roiet\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#\/schema\/logo\/image\/","url":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2019\/02\/logo101.png","contentUrl":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2019\/02\/logo101.png","width":800,"height":830,"caption":"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14"},"image":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prmuni101\/","https:\/\/www.youtube.com\/user\/roietmuni"]},{"@type":"Person","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#\/schema\/person\/8976f4ad5f8ef9e77928f898640ecb3f","name":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g","caption":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c"},"url":"https:\/\/roietmunicipal.go.th\/roiet\/author\/jitlada\/"}]}},"_links":{"self":[{"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/posts\/49681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/comments?post=49681"}],"version-history":[{"count":1,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/posts\/49681\/revisions"}],"predecessor-version":[{"id":49694,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/posts\/49681\/revisions\/49694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/media\/49685"}],"wp:attachment":[{"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/media?parent=49681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/categories?post=49681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/tags?post=49681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}