{"id":49617,"date":"2026-02-24T10:00:00","date_gmt":"2026-02-24T03:00:00","guid":{"rendered":"https:\/\/roietmunicipal.go.th\/roiet\/?p=49617"},"modified":"2026-02-24T13:17:59","modified_gmt":"2026-02-24T06:17:59","slug":"%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46","status":"publish","type":"post","link":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/","title":{"rendered":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 24 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e40\u0e27\u0e25\u0e32 10.00 \u0e19. \u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e1c\u0e28.\u0e14\u0e23.\u0e2a\u0e32\u0e18\u0e34\u0e15 \u0e01\u0e24\u0e15\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e1e\u0e34\u0e0a\u0e31\u0e22\u0e22\u0e32 \u0e15\u0e38\u0e23\u0e30\u0e0b\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e2d\u0e21\u0e21\u0e30\u0e25\u0e34 (\u0e0a\u0e31\u0e49\u0e194) \u0e28\u0e32\u0e25\u0e32\u0e01\u0e25\u0e32\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1706\" data-id=\"49620\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-5-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49620\" srcset=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-5-Copy-scaled.jpg 2560w, https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-5-Copy-scaled-360x240.jpg 360w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49619\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9487-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49619\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49623\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9493-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49623\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49618\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9495-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49618\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49626\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9498-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49626\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49621\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9504-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49621\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49622\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9509-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49622\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49625\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9526-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49625\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49627\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9530-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49627\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49624\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9535-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49624\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49628\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9546-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49628\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49631\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9549-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49631\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49629\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9557-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49629\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49630\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9563-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49630\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49632\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9565-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49632\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49633\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9572-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49633\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49634\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9575-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49634\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49635\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9578-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49635\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49637\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9581-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49637\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49636\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9585-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49636\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49638\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9590-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49638\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49639\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9592-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49639\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49640\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9595-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49640\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49641\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9597-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49641\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49642\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9603-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49642\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49644\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9606-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49644\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49643\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9611-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49643\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"49645\" src=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/IMG_9617-Copy-scaled.jpg\" alt=\"\" class=\"wp-image-49645\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 24 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e40\u0e27\u0e25\u0e32 10.00 \u0e19. \u0e19\u0e32\u0e22\u0e1a [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":49620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-49617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-7"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/roietmunicipal.go.th\/roiet\/\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07-\u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c-46\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 24 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e40\u0e27\u0e25\u0e32 10.00 \u0e19. \u0e19\u0e32\u0e22\u0e1a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/roietmunicipal.go.th\/roiet\/\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07-\u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c-46\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prmuni101\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-24T03:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T06:17:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-5-Copy-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/\"},\"author\":{\"name\":\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#\\\/schema\\\/person\\\/8976f4ad5f8ef9e77928f898640ecb3f\"},\"headline\":\"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\",\"datePublished\":\"2026-02-24T03:00:00+00:00\",\"dateModified\":\"2026-02-24T06:17:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1-5-Copy-scaled.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/\",\"name\":\"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1-5-Copy-scaled.jpg\",\"datePublished\":\"2026-02-24T03:00:00+00:00\",\"dateModified\":\"2026-02-24T06:17:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/#primaryimage\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1-5-Copy-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1-5-Copy-scaled.jpg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#website\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/\",\"name\":\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"description\":\"\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48 \u0e1c\u0e39\u0e49\u0e04\u0e19\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01 \u0e1f\u0e39\u0e21\u0e1f\u0e31\u0e01\u0e15\u0e33\u0e19\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e25\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\",\"publisher\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#organization\",\"name\":\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo101.png\",\"contentUrl\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo101.png\",\"width\":800,\"height\":830,\"caption\":\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\"},\"image\":{\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prmuni101\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/roietmuni\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/#\\\/schema\\\/person\\\/8976f4ad5f8ef9e77928f898640ecb3f\",\"name\":\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g\",\"caption\":\"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c\"},\"url\":\"https:\\\/\\\/roietmunicipal.go.th\\\/roiet\\\/author\\\/jitlada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/roietmunicipal.go.th\/roiet\/\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07-\u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c-46\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","og_description":"\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 24 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e40\u0e27\u0e25\u0e32 10.00 \u0e19. \u0e19\u0e32\u0e22\u0e1a [&hellip;]","og_url":"https:\/\/roietmunicipal.go.th\/roiet\/\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07-\u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c-46\/","og_site_name":"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","article_publisher":"https:\/\/www.facebook.com\/prmuni101\/","article_published_time":"2026-02-24T03:00:00+00:00","article_modified_time":"2026-02-24T06:17:59+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-5-Copy-scaled.jpg","type":"image\/jpeg"}],"author":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c","Est. reading time":"6 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/#article","isPartOf":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/"},"author":{"name":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#\/schema\/person\/8976f4ad5f8ef9e77928f898640ecb3f"},"headline":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25","datePublished":"2026-02-24T03:00:00+00:00","dateModified":"2026-02-24T06:17:59+00:00","mainEntityOfPage":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/"},"wordCount":0,"publisher":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/#organization"},"image":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/#primaryimage"},"thumbnailUrl":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-5-Copy-scaled.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/","url":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/","name":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 - \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","isPartOf":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/#website"},"primaryImageOfPage":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/#primaryimage"},"image":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/#primaryimage"},"thumbnailUrl":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-5-Copy-scaled.jpg","datePublished":"2026-02-24T03:00:00+00:00","dateModified":"2026-02-24T06:17:59+00:00","breadcrumb":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/#primaryimage","url":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-5-Copy-scaled.jpg","contentUrl":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2026\/02\/1-5-Copy-scaled.jpg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/roietmunicipal.go.th\/roiet\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%87-%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%b4%e0%b8%95%e0%b8%88%e0%b8%b4%e0%b8%a3%e0%b8%99%e0%b8%b1%e0%b8%99%e0%b8%97%e0%b9%8c-46\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/roietmunicipal.go.th\/roiet\/"},{"@type":"ListItem","position":2,"name":"\u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e42\u0e06\u0e29\u0e34\u0e15\u0e08\u0e34\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 (\u0e01.\u0e17.\u0e08 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25"}]},{"@type":"WebSite","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#website","url":"https:\/\/roietmunicipal.go.th\/roiet\/","name":"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","description":"\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48 \u0e1c\u0e39\u0e49\u0e04\u0e19\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01 \u0e1f\u0e39\u0e21\u0e1f\u0e31\u0e01\u0e15\u0e33\u0e19\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e25\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","publisher":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/roietmunicipal.go.th\/roiet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#organization","name":"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14","url":"https:\/\/roietmunicipal.go.th\/roiet\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#\/schema\/logo\/image\/","url":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2019\/02\/logo101.png","contentUrl":"https:\/\/roietmunicipal.go.th\/roiet\/wp-content\/uploads\/2019\/02\/logo101.png","width":800,"height":830,"caption":"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14"},"image":{"@id":"https:\/\/roietmunicipal.go.th\/roiet\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prmuni101\/","https:\/\/www.youtube.com\/user\/roietmuni"]},{"@type":"Person","@id":"https:\/\/roietmunicipal.go.th\/roiet\/#\/schema\/person\/8976f4ad5f8ef9e77928f898640ecb3f","name":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a5f9d95343b3d5eba04612e59c7bf5e1c6ab19227a1765b533924dca51db0bf?s=96&d=mm&r=g","caption":"\u0e08\u0e34\u0e15\u0e23\u0e25\u0e14\u0e32 \u0e2a\u0e38\u0e48\u0e21\u0e21\u0e32\u0e15\u0e22\u0e4c"},"url":"https:\/\/roietmunicipal.go.th\/roiet\/author\/jitlada\/"}]}},"_links":{"self":[{"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/posts\/49617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/comments?post=49617"}],"version-history":[{"count":1,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/posts\/49617\/revisions"}],"predecessor-version":[{"id":49646,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/posts\/49617\/revisions\/49646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/media\/49620"}],"wp:attachment":[{"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/media?parent=49617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/categories?post=49617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roietmunicipal.go.th\/roiet\/wp-json\/wp\/v2\/tags?post=49617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}